{"id":15008,"date":"2023-06-12T23:19:25","date_gmt":"2023-06-12T15:19:25","guid":{"rendered":"https:\/\/www.hoisi.com\/?p=15008"},"modified":"2023-12-02T20:40:11","modified_gmt":"2023-12-02T12:40:11","slug":"deguogswcgaowenzhoucheng-6019-ht2","status":"publish","type":"post","link":"https:\/\/www.hoisi.com\/index.php\/15008.html","title":{"rendered":"6019-HT2 | \u5fb7\u56fdGSWC\u8f74\u627f-GSWC\u9ad8\u6e29\u8f74\u627f"},"content":{"rendered":"\n<p class=\"has-white-color has-text-color has-background\" style=\"background-color:#335288\">\u201cSWC\u201d\u548c\u201cGSWC\u201d\u54c1\u724c\u9ad8\u6e29\u8f74\u627f\u5747\u96b6\u5c5e\u4e8e \u5fb7\u56fd\u201cSWC W\u00e4lzlagerfabrikation SW GmbH\u201d\u516c\u53f8<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:40% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-1024x1024.jpg\" alt=\"GSWC-HT2-lubrication\" class=\"wp-image-16054 size-full\" srcset=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-1024x1024.jpg 1024w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-300x300.jpg 300w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-150x150.jpg 150w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-768x768.jpg 768w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-600x600.jpg 600w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2.jpg 1470w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>\u3000\u3000\u6839\u636e\u6240\u7528\u6da6\u6ed1\u8102\u7684\u4e0d\u540c\uff0c\u6b63\u5e38\u8f74\u627f\u7684\u5b8c\u7f8e\u8fd0\u884c\u6027\u80fd\u53ea\u80fd\u4fdd\u8bc1\u6700\u9ad8150\u2103\u3002GSWC\u9ad8\u6e29\u6df1\u6c9f\u7403\u8f74\u627f\u5141\u8bb8\u5728\u4f4e\u901f\u65f6\u6e29\u5ea6\u9ad8\u8fbe350\u2103\u3002<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-cyan-blue-color\">GSWC\u9ad8\u6e29\u8f74\u627f\u4f18\u70b9<\/mark><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u6839\u636eFAG\u6807\u51c6S2\uff0c\u6e29\u5ea6\u9ad8\u8fbe250\u2103\u65f6\u7684\u70ed\u7a33\u5b9a\u6027\u3002<\/li>\n\n\n\n<li>\u589e\u52a0\u5f84\u5411\u6e38\u9699\uff08C5\u7684\u500d\u6570\uff09\uff0c\u8865\u507f\u751f\u4ea7\u8bbe\u5907\uff08\u8f68\u9053\u3001\u8fd0\u8f93\u88c5\u7f6e\uff09\u56e0\u6e29\u5ea6\u5f15\u8d77\u7684\u53d8\u5f62\u3002<\/li>\n\n\n\n<li>\u94c6\u63a5\u94a2\u677f\u4fdd\u6301\u67b6\uff0c\u5728\u4f4e\u6469\u64e6\u6761\u4ef6\u4e0b\u63d0\u4f9b\u9ad8\u7a33\u5b9a\u6027\u3002<\/li>\n\n\n\n<li>\u78f7\u9178\u9530\u6d82\u5c42\uff08\u6839\u636eEN ISO 9717\uff09\u53ef\u786e\u4fdd\u589e\u5f3a\u9632\u8150\u6027\u80fd\u3001\u826f\u597d\u7684\u6da6\u6ed1\u5242\u9644\u7740\u529b\u548c\u66f4\u597d\u7684\u8fd0\u884c\u6027\u80fd\u3002<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h4 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-cyan-blue-color\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-pale-cyan-blue-color\">\u6da6\u6ed1\u5242\u7279\u6027<\/mark><\/mark><\/h4>\n\n\n<style>.kb-row-layout-id_9f2722-af > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_9f2722-af > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_9f2722-af > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id_9f2722-af > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id_9f2722-af > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id_9f2722-af > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_9f2722-af > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id_9f2722-af > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id_9f2722-af > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id_9f2722-af > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_9f2722-af alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_2d4425-47 > .kt-inside-inner-col{display:flex;}.kadence-column_2d4425-47 > .kt-inside-inner-col,.kadence-column_2d4425-47 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_2d4425-47 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_2d4425-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_2d4425-47 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_2d4425-47{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2d4425-47{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2d4425-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_2d4425-47 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_2d4425-47{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_2d4425-47{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2d4425-47{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2d4425-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column_2d4425-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_2d4425-47{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2d4425-47{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_2d4425-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_2d4425-47 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_2d4425-47\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">HT1<\/h2>\n\n\n\n<p class=\"has-text-align-left\">\u6e29\u5ea6\u8303\u56f4\uff1a&lt; 350\u2103<br>\u7c7b\u578b\uff1a\u9ad8\u6e29\u818f<br>\u5bff\u547d\uff1a\u6700\u957f3\u5e74<br>\u7ef4\u62a4\u65f6\u95f4\uff1a2\u201318\u4e2a\u6708<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column_4a17c8-a4 > .kt-inside-inner-col{display:flex;}.kadence-column_4a17c8-a4 > .kt-inside-inner-col,.kadence-column_4a17c8-a4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_4a17c8-a4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_4a17c8-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_4a17c8-a4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_4a17c8-a4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_4a17c8-a4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_4a17c8-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_4a17c8-a4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_4a17c8-a4{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_4a17c8-a4{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_4a17c8-a4{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_4a17c8-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column_4a17c8-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_4a17c8-a4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_4a17c8-a4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_4a17c8-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_4a17c8-a4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_4a17c8-a4\"><div class=\"kt-inside-inner-col\"><style>.kb-image_ba62a4-42 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image_ba62a4-42 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT1-lubrication-2-1024x1024.jpg\" alt=\"GSWC-HT1-lubrication\" class=\"kb-img wp-image-16053\" srcset=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT1-lubrication-2-1024x1024.jpg 1024w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT1-lubrication-2-300x300.jpg 300w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT1-lubrication-2-150x150.jpg 150w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT1-lubrication-2-768x768.jpg 768w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT1-lubrication-2-600x600.jpg 600w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT1-lubrication-2.jpg 1470w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column_3f0d69-9c > .kt-inside-inner-col{display:flex;}.kadence-column_3f0d69-9c > .kt-inside-inner-col,.kadence-column_3f0d69-9c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_3f0d69-9c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_3f0d69-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_3f0d69-9c > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_3f0d69-9c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_3f0d69-9c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_3f0d69-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_3f0d69-9c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_3f0d69-9c{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_3f0d69-9c{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_3f0d69-9c{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_3f0d69-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column_3f0d69-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_3f0d69-9c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_3f0d69-9c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_3f0d69-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_3f0d69-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_3f0d69-9c\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">HT2<\/h2>\n\n\n\n<p>\u6e29\u5ea6\u8303\u56f4\uff1a&lt; 280\u2103<br>\u7c7b\u578b\uff1a\u7279\u79cd\u6da6\u6ed1\u8102<br>\u5bff\u547d\uff1a\u6700\u957f5\u5e74<br>\u7ef4\u62a4\u65f6\u95f4\uff1a\u65e0\u9700\u7ef4\u62a4<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column_9bb64e-a2 > .kt-inside-inner-col{display:flex;}.kadence-column_9bb64e-a2 > .kt-inside-inner-col,.kadence-column_9bb64e-a2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_9bb64e-a2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_9bb64e-a2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_9bb64e-a2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_9bb64e-a2{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_9bb64e-a2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_9bb64e-a2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_9bb64e-a2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_9bb64e-a2{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_9bb64e-a2{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_9bb64e-a2{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_9bb64e-a2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column_9bb64e-a2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_9bb64e-a2{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_9bb64e-a2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_9bb64e-a2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_9bb64e-a2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_9bb64e-a2\"><div class=\"kt-inside-inner-col\"><style>.kb-image_2b3417-8d .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image_2b3417-8d size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-1024x1024.jpg\" alt=\"GSWC-HT2-lubrication\" class=\"kb-img wp-image-16054\" srcset=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-1024x1024.jpg 1024w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-300x300.jpg 300w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-150x150.jpg 150w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-768x768.jpg 768w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2-600x600.jpg 600w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2-lubrication-2.jpg 1470w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id_a47ea7-c7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id_a47ea7-c7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id_a47ea7-c7 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id_a47ea7-c7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id_a47ea7-c7 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id_a47ea7-c7 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id_a47ea7-c7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id_a47ea7-c7 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id_a47ea7-c7 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id_a47ea7-c7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id_a47ea7-c7 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column_bc2645-61 > .kt-inside-inner-col{display:flex;}.kadence-column_bc2645-61 > .kt-inside-inner-col,.kadence-column_bc2645-61 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_bc2645-61 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_bc2645-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_bc2645-61 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_bc2645-61{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_bc2645-61{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_bc2645-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_bc2645-61 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_bc2645-61{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_bc2645-61{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_bc2645-61{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_bc2645-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column_bc2645-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_bc2645-61{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_bc2645-61{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_bc2645-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_bc2645-61 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_bc2645-61\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">HT2X<\/h2>\n\n\n\n<p>\u6e29\u5ea6\u8303\u56f4\uff1a&lt; 320\u2103<br>\u7c7b\u578b\uff1a\u7279\u79cd\u6da6\u6ed1\u8102<br>\u5bff\u547d\uff1a\u6700\u957f5\u5e74<br>\u7ef4\u62a4\u65f6\u95f4\uff1a\u65e0\u9700\u7ef4\u62a4<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column_390ae7-a0 > .kt-inside-inner-col{display:flex;}.kadence-column_390ae7-a0 > .kt-inside-inner-col,.kadence-column_390ae7-a0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_390ae7-a0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_390ae7-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_390ae7-a0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_390ae7-a0{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_390ae7-a0{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_390ae7-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_390ae7-a0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_390ae7-a0{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_390ae7-a0{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_390ae7-a0{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_390ae7-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column_390ae7-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_390ae7-a0{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_390ae7-a0{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_390ae7-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_390ae7-a0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_390ae7-a0\"><div class=\"kt-inside-inner-col\"><style>.kb-image_3bc5c6-d8 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image_3bc5c6-d8 size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2X-lubrication-2-1024x1024.jpg\" alt=\"GSWC-HT2X-lubrication\" class=\"kb-img wp-image-16055\" srcset=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2X-lubrication-2-1024x1024.jpg 1024w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2X-lubrication-2-300x300.jpg 300w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2X-lubrication-2-150x150.jpg 150w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2X-lubrication-2-768x768.jpg 768w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2X-lubrication-2-600x600.jpg 600w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT2X-lubrication-2.jpg 1470w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column_6d2440-9c > .kt-inside-inner-col{display:flex;}.kadence-column_6d2440-9c > .kt-inside-inner-col,.kadence-column_6d2440-9c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_6d2440-9c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_6d2440-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_6d2440-9c > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_6d2440-9c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_6d2440-9c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_6d2440-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_6d2440-9c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_6d2440-9c{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_6d2440-9c{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_6d2440-9c{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_6d2440-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column_6d2440-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_6d2440-9c{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_6d2440-9c{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_6d2440-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_6d2440-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_6d2440-9c\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">HT3<\/h2>\n\n\n\n<p>\u6e29\u5ea6\u8303\u56f4\uff1a&lt; 300\u2103<br>\u7c7b\u578b\uff1a\u56fa\u4f53\u5316\u5408\u7269<br>\u5bff\u547d\uff1a\u6700\u957f6\u5e74<br>\u7ef4\u62a4\u65f6\u95f4\uff1a\u65e0\u9700\u7ef4\u62a4<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column_fd7773-34 > .kt-inside-inner-col{display:flex;}.kadence-column_fd7773-34 > .kt-inside-inner-col,.kadence-column_fd7773-34 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column_fd7773-34 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column_fd7773-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_fd7773-34 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column_fd7773-34{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_fd7773-34{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_fd7773-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_fd7773-34 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column_fd7773-34{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column_fd7773-34{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_fd7773-34{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_fd7773-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column_fd7773-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column_fd7773-34{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_fd7773-34{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column_fd7773-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column_fd7773-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column_fd7773-34\"><div class=\"kt-inside-inner-col\"><style>.kb-image_586d1e-bd .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image_586d1e-bd size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT3-lubrication-2-1024x1024.jpg\" alt=\"GSWC-HT3-lubrication-Products\" class=\"kb-img wp-image-16056\" srcset=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT3-lubrication-2-1024x1024.jpg 1024w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT3-lubrication-2-300x300.jpg 300w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT3-lubrication-2-150x150.jpg 150w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT3-lubrication-2-768x768.jpg 768w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT3-lubrication-2-600x600.jpg 600w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/04\/GSWC-HT3-lubrication-2.jpg 1470w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n\n\n\n<p>\u3000\u3000\u6240\u6709HT1\u3001HT2\u548cHT2X\u8f74\u627f\u90fd\u662f\u5f00\u653e\u5f0f\u7684\u3001\u4e00\u4fa7\uff08ZR\uff09\u6216\u4e24\u4fa7\uff082ZR\uff09\u6709\u94a2\u677f\u9632\u5c18\u76d6\u3002HT3\u8f74\u627f\u59cb\u7ec8\u914d\u6709\u4e24\u4e2a\u94a2\u677f\u9632\u5c18\u76d6\uff082ZR\uff09\u3002<\/p>\n<\/div><\/div>\n\n\n\n<p class=\"has-white-color has-text-color has-background\" style=\"background-color:#335288\">\u5c3a\u5bf8\u53c2\u6570<\/p>\n\n\n<style>.kb-image_f7c7ca-c1.kb-image-is-ratio-size, .kb-image_f7c7ca-c1 .kb-image-is-ratio-size{max-width:122px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image_f7c7ca-c1.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image_f7c7ca-c1 .kb-image-is-ratio-size{align-self:unset;}.kb-image_f7c7ca-c1 figure{max-width:122px;}.kb-image_f7c7ca-c1 .image-is-svg, .kb-image_f7c7ca-c1 .image-is-svg img{width:100%;}.kb-image_f7c7ca-c1 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image_f7c7ca-c1\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"435\" height=\"1024\" src=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/06\/GSWC-60xx-dim-435x1024.jpg\" alt=\"GSWC-60xx-dim\" class=\"kb-img wp-image-13980\" srcset=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/06\/GSWC-60xx-dim-435x1024.jpg 435w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/06\/GSWC-60xx-dim-127x300.jpg 127w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/06\/GSWC-60xx-dim-652x1536.jpg 652w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2023\/06\/GSWC-60xx-dim.jpg 666w\" sizes=\"auto, (max-width: 435px) 100vw, 435px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td rowspan=\"2\">\u578b\u53f7<\/td><td colspan=\"4\">\u5c3a\u5bf8 [mm]<\/td><td>&nbsp;\u989d\u5b9a\u8d1f\u8f7d[kN]&nbsp;<\/td><td rowspan=\"2\">\u6781\u9650\u8f6c\u901f<br>[min<sup>-1<\/sup>]<\/td><td rowspan=\"2\">&nbsp;\u91cd\u91cf<br>\u2248[kg]&nbsp;<\/td><\/tr><tr><td>d<\/td><td>D<\/td><td>B<\/td><td>&nbsp;r<sub>s<\/sub>(min)&nbsp;<\/td><td>&nbsp;C<sub>o<\/sub>&nbsp;<\/td><\/tr><tr><td><strong>6019-HT2<\/strong><\/td><td>95<\/td><td>145<\/td><td>24<\/td><td>&nbsp;1.5&nbsp;<\/td><td>&nbsp;54.00&nbsp;<\/td><td>50<\/td><td>&nbsp;1.070&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center has-small-font-size\">\u5907\u6ce8\uff1a\u91cd\u91cf\u4ec5\u9002\u7528\u4e8e\u6ca1\u6709\u6da6\u6ed1\u5242\u548c\u5bc6\u5c01\u76d6\u7684\u8f74\u627f<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#335288\"><\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-corecolumns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:60%\">\n<p class=\"has-text-align-center\" style=\"font-size:16px\">\u3016 <strong><mark style=\"background-color:rgba(0, 0, 0, 0);color:#00923f\" class=\"has-inline-color\">\u6280\u672f\u54a8\u8be2\u53ca\u4ea7\u54c1\u8d2d\u4e70\uff0c\u8bf7\u8054\u7cfb \u201c<a href=\"https:\/\/www.hoisi.com\/index.php\/contact#Contactus\" target=\"_blank\" rel=\"noreferrer noopener\">\u51ef\u72ee\u7cbe\u5bc6<\/a>\u201d \u9500\u552e\u5de5\u7a0b\u5e08<\/mark><\/strong> \u3017<\/p>\n\n\n\n<p class=\"has-text-align-center has-text-color\" style=\"color:#028239;font-size:14px\"><strong>\u9500\u552e\u7ecf\u7406\uff1a\u8d75\u56fd\u8fdb <\/strong>\u5148\u751f<strong>\u3000\u3000\/\u3000\u3000\u8054\u7cfb\u7535\u8bdd\uff1a180 7312 9830<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><style>.kb-image7922_6d8bc7-ed.kb-image-is-ratio-size, .kb-image7922_6d8bc7-ed .kb-image-is-ratio-size{max-width:115px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image7922_6d8bc7-ed.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image7922_6d8bc7-ed .kb-image-is-ratio-size{align-self:unset;}.kb-image7922_6d8bc7-ed{max-width:115px;}.image-is-svg.kb-image7922_6d8bc7-ed{-webkit-flex:0 1 100%;flex:0 1 100%;}.image-is-svg.kb-image7922_6d8bc7-ed img{width:100%;}.kb-image7922_6d8bc7-ed .kb-image-has-overlay:after{opacity:0.3;}.kb-image7922_6d8bc7-ed img.kb-img, .kb-image7922_6d8bc7-ed .kb-img img{box-shadow:0px 0px 14px 0px rgba(0, 0, 0, 0.2);}<\/style>\n<figure class=\"wp-block-kadence-image kb-image7922_6d8bc7-ed size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"733\" height=\"733\" src=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2022\/11\/wechat-18073129830-374X374-B.webp\" alt=\"18073129830\" class=\"kb-img wp-image-24792\" srcset=\"https:\/\/www.hoisi.com\/wp-content\/uploads\/2022\/11\/wechat-18073129830-374X374-B.webp 733w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2022\/11\/wechat-18073129830-374X374-B-300x300.webp 300w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2022\/11\/wechat-18073129830-374X374-B-150x150.webp 150w, https:\/\/www.hoisi.com\/wp-content\/uploads\/2022\/11\/wechat-18073129830-374X374-B-600x600.webp 600w\" sizes=\"auto, (max-width: 733px) 100vw, 733px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:20%\"><style>.wp-block-kadence-advancedbtn.kb-btns7922_cbe484-70{gap:var(--global-kb-gap-xs, 0.5rem );justify-content:center;align-items:center;}.kt-btns7922_cbe484-70 .kt-button{font-weight:normal;font-style:normal;}.kt-btns7922_cbe484-70 .kt-btn-wrap-0{margin-right:5px;}.wp-block-kadence-advancedbtn.kt-btns7922_cbe484-70 .kt-btn-wrap-0 .kt-button{color:#555555;border-color:#555555;}.wp-block-kadence-advancedbtn.kt-btns7922_cbe484-70 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns7922_cbe484-70 .kt-btn-wrap-0 .kt-button:focus{color:#ffffff;border-color:#444444;}.wp-block-kadence-advancedbtn.kt-btns7922_cbe484-70 .kt-btn-wrap-0 .kt-button::before{display:none;}.wp-block-kadence-advancedbtn.kt-btns7922_cbe484-70 .kt-btn-wrap-0 .kt-button:hover, .wp-block-kadence-advancedbtn.kt-btns7922_cbe484-70 .kt-btn-wrap-0 .kt-button:focus{background:#444444;}<\/style>\n<div class=\"wp-block-kadence-advancedbtn kb-buttons-wrap kb-btns7922_cbe484-70\"><style>ul.menu .wp-block-kadence-advancedbtn .kb-btn7922_73efe5-27.kb-button{width:initial;}<\/style><span class=\"kb-button kt-button button kb-btn7922_73efe5-27 kt-btn-size-large kt-btn-width-type-auto kb-btn-global-inherit  kt-btn-has-text-true kt-btn-has-svg-true  wp-block-button__link wp-block-kadence-singlebtn\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_th-list kt-btn-icon-side-left\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M149.333 216v80c0 13.255-10.745 24-24 24H24c-13.255 0-24-10.745-24-24v-80c0-13.255 10.745-24 24-24h101.333c13.255 0 24 10.745 24 24zM0 376v80c0 13.255 10.745 24 24 24h101.333c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H24c-13.255 0-24 10.745-24 24zM125.333 32H24C10.745 32 0 42.745 0 56v80c0 13.255 10.745 24 24 24h101.333c13.255 0 24-10.745 24-24V56c0-13.255-10.745-24-24-24zm80 448H488c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H205.333c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24zm-24-424v80c0 13.255 10.745 24 24 24H488c13.255 0 24-10.745 24-24V56c0-13.255-10.745-24-24-24H205.333c-13.255 0-24 10.745-24 24zm24 264H488c13.255 0 24-10.745 24-24v-80c0-13.255-10.745-24-24-24H205.333c-13.255 0-24 10.745-24 24v80c0 13.255 10.745 24 24 24z\"\/><\/svg><\/span><span class=\"kt-btn-inner-text\">\u8bf7\u6c42\u62a5\u4ef7<\/span><\/span><\/div>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n","protected":false},"excerpt":{"rendered":"<p>\u201cSWC\u201d\u548c\u201cGSWC\u201d\u54c1\u724c\u9ad8\u6e29\u8f74\u627f\u5747\u96b6\u5c5e\u4e8e \u5fb7\u56fd\u201cSWC W\u00e4lzlagerfabrikation SW G [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"ocs-productpage_sidebar_gswc","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[315,4,318],"tags":[185],"class_list":["post-15008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gswc","category-products","category-gswc_high-temp_deep_groove_ball_bearings","tag-gaowenzhoucheng","entry","has-media"],"_links":{"self":[{"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/posts\/15008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/comments?post=15008"}],"version-history":[{"count":0,"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/posts\/15008\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/media\/14819"}],"wp:attachment":[{"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/media?parent=15008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/categories?post=15008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hoisi.com\/index.php\/wp-json\/wp\/v2\/tags?post=15008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}